{"id":5642,"date":"2020-09-22T15:17:46","date_gmt":"2020-09-22T14:17:46","guid":{"rendered":"https:\/\/ezfactory.nl\/2020\/09\/22\/the-happy-operator\/"},"modified":"2025-03-26T14:55:51","modified_gmt":"2025-03-26T13:55:51","slug":"der-glueckliche-bediener","status":"publish","type":"post","link":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/","title":{"rendered":"Der gl\u00fcckliche Bediener"},"content":{"rendered":"<p><strong>Wolfgang ist <em>Projektleiter Digitalisierung Betrieblicher Prozesse<\/em> des fiktiven deutschen Softdrinkunternehmens Jungle Power. In den Niederlanden macht er sich mit der digitalen Bediener-App EZ-GO vertraut. Er ist noch keineswegs von dem Nutzen der App \u00fcberzeugt, aber ein Treffen mit der Bedienerin Bianca, einer temperamentvollen Dame, die kein Blatt vor den Mund nimmt, wird das bald \u00e4ndern. <\/strong><\/p>\n<p>Zwei Wochen zuvor hat Wolfgang ein langes Telefongespr\u00e4ch mit John Veldman gef\u00fchrt, Teamleiter in der niederl\u00e4ndischen Fabrik des Herstellers von Jungle Power, eines gesunden Erfrischungsgetr\u00e4nk, und begeisterter Nutzer der App. John sprach immer wieder von den gro\u00dfen Vorteilen, aber Wolfgang ist ein vern\u00fcnftiger Mann, der nicht alles glaubt, was man ihm erz\u00e4hlt &#8211; schon gar nicht am Telefon. Er wird heute in der Fabrik in Veghel herumgef\u00fchrt und ist kritisch eingestellt. Denn wenn er dieser App tats\u00e4chlich zustimmt, werden sie sie in allen sechzig Fabriken von Jungle Power weltweit einsetzen &#8211; keine leichte Entscheidung, und er will keine Fehler machen.<\/p>\n<h2>Flie\u00dfende Prozesse<\/h2>\n<p>John empf\u00e4ngt ihn herzlich, bietet ihm sogar eine gute Tasse Kaffee mit Kuchen an (die Holl\u00e4nder lernen es so langsam), wonach sie eine Treppe zur Aussichtsplattform hinaufsteigen, von der aus man die ganze Fabrik \u00fcberblicken kann. Wolfgang muss es zugegeben, alles sieht sehr durchorganisiert aus. Doch das ist an ihrem deutschen Hauptstandort auch der Fall, und daf\u00fcr brauchen sie keine App.<\/p>\n<p>John Veldman beginnt begeistert, \u00fcber den Umsetzungsprozess zu erz\u00e4hlen, in hervorragendem Deutsch. Trotzdem f\u00e4llt es Wolfgang schwer zuzuh\u00f6ren, da seine Aufmerksamkeit auf den Arbeitsbereich gelenkt wird. Wie die Menschen dort st\u00e4ndig in Bewegung sind, aber nie in Eile zu sein scheinen, es ist ein flie\u00dfender Prozess, fast ein Tanz. Er sch\u00fcttelt den Kopf und ruft sich zur Ordnung. Du bist nicht hier, um poetisch zu sein, Wolfgang, du hei\u00dft nicht Goethe, bleib sachlich.<\/p>\n<h2>In der Praxis<\/h2>\n<p>Wolfgang unterbricht John mitten in einem Satz \u00fcber die Tonnen Papier, die sie jetzt einsparen. \u201eK\u00f6nnen wir uns das nicht einfach in der Praxis angucken?\u201c, fragt er.<\/p>\n<p>John strahlt. \u201eSehr gerne.\u201c<\/p>\n<p>\u201eDann w\u00fcrde ich gerne mit einem Bediener sprechen, sozusagen an der Quelle anfangen.\u201c<\/p>\n<p>\u201eDas ist \u00fcberhaupt kein Problem. Wir m\u00fcssen uns nur eben Schutzkleidung \u00fcberziehen.\u201c<\/p>\n<p>Im Umkleideraum klickt John auf einen Bildschirm, auf dem ein Video Schritt f\u00fcr Schritt zeigt, wo sich die Overalls, Haarnetze und Schuh\u00fcberz\u00fcge befinden und wie man sie anzieht.<\/p>\n<p>\u201eIst das, \u00e4h&#8230;\u201c, beginnt Wolfang.<\/p>\n<p>\u201eEZ-GO, ja, jetzt da Sie es sagen.\u201c<\/p>\n<p>Einmal in der Fabrik sieht sich Wolfgang die verschiedenen Bediener erstmal von Weitem an. Er m\u00f6chte mit der Person sprechen, die am seri\u00f6sesten guckt. \u201eDie Frau dort, mit dem strengen Pferdeschwanz, an der Verpackungslinie.\u201c<\/p>\n<p>\u201eDas ist Bianca\u201c, sagt John, \u201eeine unserer besten Bedienerinnen. Sind Sie sich sicher?\u201c<\/p>\n<p>\u201eWarum, was meinen Sie?\u201c<\/p>\n<p>\u201eSie nimmt ihre Arbeit sehr ernst und wird nicht gerne unterbrochen.\u201c<\/p>\n<p>\u201eUmso besser, stellen Sie mich ihr vor.\u201c<\/p>\n<h2>Bianca<\/h2>\n<p>Bianca arbeitet ungest\u00f6rt weiter, w\u00e4hrend sie Wolfgangs Fragen kurz und knapp beantwortet. Wie lange sie schon hier arbeitet. Vierzehn Jahre. Ob sie mit der App zufrieden ist. Ja. Inwieweit sich ihre Arbeit dadurch verbessert hat. Jetzt h\u00e4lt sie kurz inne und sieht Wolfgang streng an, ohne die Mundwinkel zu verziehen, mit stechenden gr\u00fcnen Augen, w\u00e4hrend sie ein iPad herauszieht. \u201eSchauen Sie mir doch einfach zu. Dann spar ich mir die Zeit f\u00fcr lange Erkl\u00e4rungen und werden alle Ihre Fragen gleich beantwortet.\u201c<\/p>\n<p>Obwohl sie es auf Niederl\u00e4ndisch gesagt hat, versteht er, was sie meint, und es f\u00e4llt ihm nicht ein, ihr zu widersprechen. Er schaut also zu.<\/p>\n<p>\u201eSie haben Gl\u00fcck, denn dies ist der Abschluss der Reinigungs- und Inspektionstour am Ende der Woche. Das sind zehn Inspektionen, die sicherstellen, dass meine Linie f\u00fcr das Wochenende in einem Top-Zustand ist und bleibt. Wir wollen doch keine Probleme beim Beginn der Wochenendschicht, oder?\u201c<\/p>\n<p>Nein, nein, sicher nicht\u201c, stimmt Wolfgang schnell zu.<\/p>\n<p>Sie zeigt ihm die EZ-GO-App auf einem iPad, klickt auf die Schaltfl\u00e4che <em>Checklist End of Week Cleaning &amp; Inspection<\/em> und es erscheint eine \u00dcbersicht der Punkte, von denen sie den ersten \u00f6ffnet: <em>Cleaning 3 sensors packing machine<\/em>.<\/p>\n<p>\u201eAuf Englisch?\u201c, fragt Wolfgang.<\/p>\n<p>Sie schaut auf. \u201eDenken Sie vielleicht, dass ich kein Englisch kann? Es arbeiten hier auch Menschen aus dem Ostblock, und aus Spanien und Somalia und was wei\u00df ich woher noch \u00fcberall. Die m\u00fcssen das doch auch verstehen k\u00f6nnen?\u201c<\/p>\n<p>\u201eJa, nat\u00fcrlich, Frau Bianca.\u201c<\/p>\n<h2>Pr\u00fcfen, verbessern, verhindern<\/h2>\n<p>Auf dem Bildschirm erscheint eine Reihe von Bildern: drei Sensoren und die Art und Weise, wie sie sauber gewischt werden sollten. Es ist eine Frage von Sekunden; routinem\u00e4\u00dfig macht sich Bianca an die Arbeit und hakt auf dem Bildschirm alles ab. \u201eFertig. M\u00f6chten Sie noch mehr sehen oder kann ich weiterarbeiten?\u201c<\/p>\n<p>\u201eIch w\u00fcrde gerne noch mehr sehen.\u201c<\/p>\n<p>Ihr Finger bleibt kurz \u00fcber dem n\u00e4chsten Punkt auf dem Bildschirm h\u00e4ngen:<em> Remove glue residue<\/em>. Zum ersten Mal huscht ein L\u00e4cheln \u00fcber ihr Gesicht. \u201eDas ist ein guter Aktionspunkt\u201c, sagt sie. \u201eEcht toll. Jahrelang hatten wir immer wieder Probleme mit dieser Kartonklebemaschine. Auf den Rollen des F\u00f6rderbandes blieben Leimreste zur\u00fcck, wodurch das Band immer schlechter lief. Bis wir einmal einen f\u00fcnfst\u00fcndigen Stillstand hatten, weil das F\u00f6rderband gerissen war. F\u00fcnf Stunden! Wissen Sie, wie viele Kartons das sind? Das Band war nicht vorr\u00e4tig, wir mussten also auf ein neues Band warten &#8211; sie kennen das bestimmt.\u201c<\/p>\n<p>Er hat keine Ahnung, nickt aber mitf\u00fchlend.<\/p>\n<p>\u201eJedenfalls haben wir, als das behoben war, einen Zettel an die Maschine geh\u00e4ngt: <em>In jeder Schicht Leimreste entfernen.<\/em> Und was denken Sie?\u201c Sie wartet seine Antwort nicht ab. \u201eDas machte niemand, au\u00dfer mir. Manchmal. Nun gut, ein halbes Jahr sp\u00e4ter: Band wieder kaputt, neues Band n\u00f6tig, nicht vorr\u00e4tig, Eilbestellung aufgegeben &#8211; wieder eine Schicht lang Stillstand. Neuen Zettel ausgedruckt, in grellen Farben und mit Ausrufezeichen. Aber sie raten es bestimmt schon.\u201c<\/p>\n<p>\u201eNiemand entfernte die Leimreste, au\u00dfer Ihnen.\u201c<\/p>\n<p>Sie nickt. \u201eUnd dann kam John mit seiner App. Ich dachte noch, was soll ich denn jetzt damit? Ich bin \u00fcberhaupt nicht technisch und wir m\u00fcssen einfach nur saubermachen, warum verstehen die anderen Kollegen das nicht? Doch John hat sich durchgesetzt, und jetzt bin ich froh. Entschuldigung, das war eine lange Erkl\u00e4rung, aber ich zeige es Ihnen jetzt.\u201c Sie \u00f6ffnet den Arbeitsschritt <em>Remove glue residue<\/em>. Es erscheint ein Video von weniger als zehn Sekunden, das zeigt, wie die Leimreste an der Unterseite des Bandes entfernt werden, damit sie sich dort nicht ansammeln k\u00f6nnen. Bianca f\u00fchrt den Arbeitsschritt aus, hakt ihn ab und schaut Wolfgang an.<\/p>\n<p>\u201eIst das alles?\u201c, fragt er und bereut es sofort.<\/p>\n<p>Bianca guckt ihn streng an. \u201eAlles? Das erspart uns tagelange Produktionszeit pro Jahr! Au\u00dferdem l\u00e4uft die Maschine besser. Und wodurch?\u201c Durch einen Arbeitsschritt von wenigen Sekunden. In der ersten Version der App war das noch eine allt\u00e4gliche Aktion, aber weil das jetzt jeder machte, wurde die Maschine nicht mehr so schmutzig und konnten wir es auf zweimal pro Woche reduzieren. Dann fragte ich mich, ob es nicht auch am Leim lag, und das habe ich dann in der App gemeldet. Schauen Sie, das ist hier m\u00f6glich.\u201c Sie zeigt ihm die Schaltfl\u00e4che <em>Aktion melden<\/em>. \u201eEs stellte sich heraus, dass es inzwischen tats\u00e4chlich besseren Leim gab. Jetzt m\u00fcssen wir das Band also nur noch einmal pro Woche reinigen. Verstehen Sie?\u201c<\/p>\n<p>Wolfgang versteht es sogar sehr gut. In seinem Kopf beginnt er bereits zu berechnen, welche Vorteile sie damit erzielen k\u00f6nnen, aber bevor er zu einem Ergebnis kommt, l\u00e4utet eine Glocke.<\/p>\n<p>\u201eKaffee!\u201c, freut sich Bianca. \u201eIch hake noch schnell die Punkte ab, wenn es Ihnen nichts ausmacht.\u201c<\/p>\n<p>Wolfgang schaut neben sich und bemerkt erst jetzt, dass John auch noch da ist.<\/p>\n<p>Der lacht: \u201eVerstehen Sie nun, warum ich Sie gebeten habe, sich das alles einmal in der Praxis anzusehen? Die Menschen hier am Arbeitsplatz stehen wirklich dahinter, wir m\u00fcssen kaum etwas daf\u00fcr tun, um sie zu \u00fcberzeugen.\u201c<\/p>\n<p>Wolfgang nickt. \u201eSag ruhig Du.\u201c<\/p>\n<h2>Gl\u00fcck findet sich &#8230; in einem leeren Abfalleimer<\/h2>\n<p>\u201eVielen Dank, Frau Bianca\u201c, sagt Wolfgang. \u201eSie hatten Recht, das beantwortet alle meine Fragen.\u201c<\/p>\n<p>\u201eNein, nein\u201c, sagt sie, w\u00e4hrend sie in Ruhe die letzten Kontrollen ausf\u00fchrt. \u201eSie haben ja keine Ahnung. Sehen Sie diesen Abfalleimer dort dr\u00fcben, mit den Folienresten? Sie zeigt auf einen leuchtend gelben Beh\u00e4lter. \u201eDer war fr\u00fcher immer voll, die Folie lag sogar oft daneben auf dem Boden. Ich glaube, jemand aus Ihrem B\u00fcro ist sogar mal dar\u00fcber gestolpert. Jetzt ist das ein Aktionspunkt in der EZ-GO-App, und zwar zu Beginn jeder Schicht. Der Leimbeh\u00e4lter: immer leer, als meine Schicht anfing. Jetzt ist auch das ein Aktionspunkt in der EZ-GO-App, am Ende jeder Schicht, sodass die Mitarbeiter der n\u00e4chsten Schicht sofort starten k\u00f6nnen. Und sehen Sie diesen alten Computer dort, der schon ein bisschen Staub ansetzt? Dort mussten wir fr\u00fcher alle Punkte f\u00fcr die Erstwartung und Checklisten abholen: erst suchen, welche f\u00fcr deine Schicht die richtige war, dann versuchen, sich das zu merken, lieber doch ausdrucken, die Aufgaben und Kontrollen durchf\u00fchren, zur\u00fcck zum Computer, abhaken, speichern. Und wenn man etwas melden wollte, musste man auch einen Aktionspunkt erstellen und ihn per E-Mail verschicken, ein Foto hochladen &#8211; damit habe ich nicht mal mehr angefangen.<\/p>\n<h2>Die Einarbeitung ist ein Kinderspiel<\/h2>\n<p>\u201eUnd wissen Sie, was ich am schlimmsten fand?\u201c Sie schaut ihn kurz \u00fcber die Schulter hinweg an. \u201eJemanden einarbeiten. Diese Arbeitsanweisungen waren in Ordnern, sie lagen dort unter dem Computer in einer Schublade und sie waren immer, aber auch wirklich immer veraltet. Derjenige, der einen anderen Mitarbeiter einarbeiten musste, war also der Dumme. Der konnte diese Arbeitsanweisungen dann jedes Mal anpassen. Sie k\u00f6nnen sich nicht vorstellen, wie viel Zeit mich das gekostet hat! Und diese neuen Mitarbeiter machten nat\u00fcrlich auch immer Fehler, denn die konnten sich das alles nicht merken. Jetzt, mit dieser App? Ich begleite sie einmal, zeige ihnen, wie es geht, und beim zweiten Mal machen sie es mit der App einfach selbst. Super easy, dieses EZ.\u201c Sie muss \u00fcber ihren eigenen Witz lachen.<\/p>\n<p>Wolfgang wird ganz still. Daran war wirklich nicht zu r\u00fctteln.<\/p>\n<p>Bianca legt das iPad weg, beugt sich ganz nah zu Wolfgang her\u00fcber und zwinkert. \u201eWirklich wahr, sogar Sie k\u00f6nnten das.\u201c Dann dreht sie sich um und geht strammen Schrittes zur Kantine.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Das ist der siebte Teil einer Serie \u00fcber das fiktive Unternehmen Jungle Power Drinks. Indem wir die Erfahrungen dieses Unternehmens mit der autonomen Instandhaltung und der EZ-GO-App beschreiben, zeigen wir, welche M\u00f6glichkeiten es gibt, die Sicherheit, Qualit\u00e4t und Produktivit\u00e4t des Betriebs zu verbessern. Lesen Sie hier Teil <\/em><a href=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/erhoehung-der-sicherheit-effizienz-und-arbeitszufriedenheit-durch-autonome-instandhaltung\/\"><em>eins<\/em><\/a><em>, <\/em><a href=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/autonome-instandhaltung-der-start-entscheidet-ueber-den-erfolg\/\"><em>zwei<\/em><\/a><em>, <\/em><a href=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/mit-autonomer-instandhaltung-sicher-sauber-und-ohne-stoerungen-arbeiten-wie-sorgen-sie-dafuer-dass-es-so-bleibt\/\"><em>drei<\/em><\/a><em>, <\/em><a href=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-operations-director-kommt-zur-inspektion-kein-problem\/\"><em>vier<\/em><\/a><em>, <\/em><a href=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-operations-director-und-das-geheimnis-der-30-igen-produktivitaetssteigerung\/\"><em>f\u00fcnf<\/em><\/a><em> und <\/em><a href=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/eine-explodierende-nachfrage-problemlos-erfuellen\/\"><em>sechs<\/em><\/a><em>.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Randy Appiah<\/em><\/p>\n<p><em>Robert Bouwman<\/em><\/p>\n<p><em>Gr\u00fcnder EZ Factory<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Wenn Sie weitere Informationen zur Implementierung der autonomen Wartung in Ihrem Werk w\u00fcnschen oder die n\u00e4chste Stufe erreichen m\u00f6chten, kann Ihnen unser Partner Pontifexx helfen. Besuchen Sie die Website f\u00fcr weitere Informationen: <a href=\"https:\/\/www.pontifexx.nl\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.pontifexx.nl\/<\/a>.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3574 aligncenter\" src=\"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/04\/p2_50.png?resize=300%2C96&#038;ssl=1\" alt=\"Pontifexx Autonomous Maintenance Continuous Improvement\" width=\"300\" height=\"96\" srcset=\"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/04\/p2_50.png?resize=300%2C96&amp;ssl=1 300w, https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/04\/p2_50.png?resize=20%2C6&amp;ssl=1 20w, https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/04\/p2_50.png?resize=190%2C61&amp;ssl=1 190w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wolfgang ist Projektleiter Digitalisierung Betrieblicher Prozesse des fiktiven deutschen Softdrinkunternehmens Jungle Power. In den Niederlanden macht er sich mit der digitalen Bediener-App EZ-GO vertraut. Er ist noch keineswegs von dem Nutzen der App \u00fcberzeugt, aber ein Treffen mit der Bedienerin Bianca, einer temperamentvollen Dame, die kein Blatt vor den Mund nimmt, wird das bald \u00e4ndern.&hellip;<\/p>\n","protected":false},"author":19,"featured_media":13662,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[140],"tags":[],"class_list":["post-5642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der gl\u00fcckliche Bediener - EZ Factory<\/title>\n<meta name=\"description\" content=\"Lesen Sie, wie die EZ GO-Plattform zu zufriedenen Bedienern und einem reibungsloseren und sichereren Produktionsprozess beitr\u00e4gt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der gl\u00fcckliche Bediener - EZ Factory\" \/>\n<meta property=\"og:description\" content=\"Lesen Sie, wie die EZ GO-Plattform zu zufriedenen Bedienern und einem reibungsloseren und sichereren Produktionsprozess beitr\u00e4gt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/\" \/>\n<meta property=\"og:site_name\" content=\"EZ Factory\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EZFactory\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T14:17:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T13:55:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/09\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nwdrezf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ezfactorynl\" \/>\n<meta name=\"twitter:site\" content=\"@ezfactorynl\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"nwdrezf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/\"},\"author\":{\"name\":\"nwdrezf\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#\\\/schema\\\/person\\\/13aed084d5d936d834e18dd2367ea105\"},\"headline\":\"Der gl\u00fcckliche Bediener\",\"datePublished\":\"2020-09-22T14:17:46+00:00\",\"dateModified\":\"2025-03-26T13:55:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/\"},\"wordCount\":1860,\"publisher\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/ezfactory.nl\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1\",\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/\",\"url\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/\",\"name\":\"Der gl\u00fcckliche Bediener - EZ Factory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/ezfactory.nl\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1\",\"datePublished\":\"2020-09-22T14:17:46+00:00\",\"dateModified\":\"2025-03-26T13:55:51+00:00\",\"description\":\"Lesen Sie, wie die EZ GO-Plattform zu zufriedenen Bedienern und einem reibungsloseren und sichereren Produktionsprozess beitr\u00e4gt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ezfactory.nl\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ezfactory.nl\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/knowledge-base\\\/der-glueckliche-bediener\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der gl\u00fcckliche Bediener\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/\",\"name\":\"Easy Factory\",\"description\":\"Digital checklists, tasks, audits &amp; work instructions\",\"publisher\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#organization\",\"name\":\"EZ Factory\",\"url\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ezfactory.nl\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo.png?fit=576%2C190&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ezfactory.nl\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo.png?fit=576%2C190&ssl=1\",\"width\":576,\"height\":190,\"caption\":\"EZ Factory\"},\"image\":{\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EZFactory\\\/\",\"https:\\\/\\\/x.com\\\/ezfactorynl\",\"https:\\\/\\\/www.instagram.com\\\/ezfactorynl\\\/\",\"https:\\\/\\\/nl.linkedin.com\\\/company\\\/ez-factory\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCaEhfWjdc6tuDn4HzYTF1zQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ezfactory.nl\\\/de\\\/#\\\/schema\\\/person\\\/13aed084d5d936d834e18dd2367ea105\",\"name\":\"nwdrezf\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der gl\u00fcckliche Bediener - EZ Factory","description":"Lesen Sie, wie die EZ GO-Plattform zu zufriedenen Bedienern und einem reibungsloseren und sichereren Produktionsprozess beitr\u00e4gt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/","og_locale":"de_DE","og_type":"article","og_title":"Der gl\u00fcckliche Bediener - EZ Factory","og_description":"Lesen Sie, wie die EZ GO-Plattform zu zufriedenen Bedienern und einem reibungsloseren und sichereren Produktionsprozess beitr\u00e4gt.","og_url":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/","og_site_name":"EZ Factory","article_publisher":"https:\/\/www.facebook.com\/EZFactory\/","article_published_time":"2020-09-22T14:17:46+00:00","article_modified_time":"2025-03-26T13:55:51+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/09\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1","type":"image\/jpeg"}],"author":"nwdrezf","twitter_card":"summary_large_image","twitter_creator":"@ezfactorynl","twitter_site":"@ezfactorynl","twitter_misc":{"Verfasst von":"nwdrezf","Gesch\u00e4tzte Lesezeit":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/#article","isPartOf":{"@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/"},"author":{"name":"nwdrezf","@id":"https:\/\/ezfactory.nl\/de\/#\/schema\/person\/13aed084d5d936d834e18dd2367ea105"},"headline":"Der gl\u00fcckliche Bediener","datePublished":"2020-09-22T14:17:46+00:00","dateModified":"2025-03-26T13:55:51+00:00","mainEntityOfPage":{"@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/"},"wordCount":1860,"publisher":{"@id":"https:\/\/ezfactory.nl\/de\/#organization"},"image":{"@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/09\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1","articleSection":["Nachrichten"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/","url":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/","name":"Der gl\u00fcckliche Bediener - EZ Factory","isPartOf":{"@id":"https:\/\/ezfactory.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/#primaryimage"},"image":{"@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/09\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1","datePublished":"2020-09-22T14:17:46+00:00","dateModified":"2025-03-26T13:55:51+00:00","description":"Lesen Sie, wie die EZ GO-Plattform zu zufriedenen Bedienern und einem reibungsloseren und sichereren Produktionsprozess beitr\u00e4gt.","breadcrumb":{"@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/#primaryimage","url":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/09\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/09\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/ezfactory.nl\/de\/knowledge-base\/der-glueckliche-bediener\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ezfactory.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Der gl\u00fcckliche Bediener"}]},{"@type":"WebSite","@id":"https:\/\/ezfactory.nl\/de\/#website","url":"https:\/\/ezfactory.nl\/de\/","name":"Easy Factory","description":"Digital checklists, tasks, audits &amp; work instructions","publisher":{"@id":"https:\/\/ezfactory.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ezfactory.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/ezfactory.nl\/de\/#organization","name":"EZ Factory","url":"https:\/\/ezfactory.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/ezfactory.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2019\/02\/logo.png?fit=576%2C190&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2019\/02\/logo.png?fit=576%2C190&ssl=1","width":576,"height":190,"caption":"EZ Factory"},"image":{"@id":"https:\/\/ezfactory.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EZFactory\/","https:\/\/x.com\/ezfactorynl","https:\/\/www.instagram.com\/ezfactorynl\/","https:\/\/nl.linkedin.com\/company\/ez-factory","https:\/\/www.youtube.com\/channel\/UCaEhfWjdc6tuDn4HzYTF1zQ"]},{"@type":"Person","@id":"https:\/\/ezfactory.nl\/de\/#\/schema\/person\/13aed084d5d936d834e18dd2367ea105","name":"nwdrezf"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ezfactory.nl\/wp-content\/uploads\/2020\/09\/autonomous-part-7-min.jpg?fit=2560%2C1920&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/posts\/5642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/comments?post=5642"}],"version-history":[{"count":7,"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/posts\/5642\/revisions"}],"predecessor-version":[{"id":18952,"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/posts\/5642\/revisions\/18952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/media\/13662"}],"wp:attachment":[{"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/media?parent=5642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/categories?post=5642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ezfactory.nl\/de\/wp-json\/wp\/v2\/tags?post=5642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}